{"id":9826,"date":"2025-08-15T14:31:39","date_gmt":"2025-08-15T12:31:39","guid":{"rendered":"https:\/\/impact.be\/candidati\/lucru-temporar\/"},"modified":"2025-11-14T18:30:42","modified_gmt":"2025-11-14T17:30:42","slug":"lucru-temporar","status":"publish","type":"page","link":"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/","title":{"rendered":"Lucru temporar"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;bottom&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;image&#8221; row_height=&#8221;row_900px&#8221; bg_color=&#8221;bg_gray&#8221; bg_custom_img=&#8221;1942&#8243; css=&#8221;.vc_custom_1759405268187{background-color: bg_gray !important;}&#8221;][vc_column width=&#8221;2\/5&#8243;]\n        <div class=\"sd-block-breadcrumb  align-left color-white marginbottom-60px\n        \">\n            <ul id=\"breadcrumbs\" class=\"breadcrumbs\"><\/ul>\n        <\/div>\n        <div class=\"sd-block-title \">\n            <h1 class=\"sd-block-title-htag  marginbottom-30px align-left color-white\n            \">\n\t\t\t\t\n            \tDe ce ar trebui s\u0103 lucra\u021bi ca angajat temporar?\n\t\t\t<\/h1>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-0px color-white\n        \">\n        \t\n            <p>Munca interimar\u0103 a evoluat mult de-a lungul anilor. Ast\u0103zi, \u00een calitate de angajat temporar, ave\u021bi dreptul la acelea\u0219i beneficii ca un angajat permanent. IMPACT v\u0103 ajut\u0103 s\u0103 \u00eencepe\u021bi cu dreptul \u0219i s\u0103 g\u0103si\u021bi un loc de munc\u0103 potrivit, complet adaptat nevoilor dumneavoastr\u0103.<\/p>\n\n        <\/div>[\/vc_column][vc_column width=&#8221;3\/5&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\n        <div class=\"sd-block-image image-count-1  align-Left marginbottom-60px\n        \"><img decoding=\"async\" title=\"\" alt=\"\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/Meer_afwisseling.jpg\">\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;]\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \tMai mult\u0103 varietate \u0219i libertate ...\n\t\t\t<\/h2>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>G\u0103sirea unei slujbe \u0219i a unui loc de munc\u0103 care vi se potrivesc este o adev\u0103rat\u0103 provocare. Ca angajat temporar, ave\u021bi \u0219ansa de a alege dintr-o varietate de op\u021biuni, de a v\u0103 spori cuno\u0219tin\u021bele \u0219i experien\u021ba \u0219i de a v\u0103 extinde re\u021beaua.<\/p>\n<p>IMPACT organizeaz\u0103 \u00eentregul proces pentru dvs., dar r\u0103m\u00e2ne\u021bi \u00eentotdeauna responsabil de propria carier\u0103.<\/p>\n\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-background button-size-normal background-color-green mobile_marginbottom-30px\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/impact.be\/ro\/candidati\/toate-posturile-vacante\/\" title=\"Descoper\u0103 toate locurile de munc\u0103\">\n                <div class=\"button-content\">\n                    <span>Descoper\u0103 toate locurile de munc\u0103<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \tRe\u021bea extins\u0103\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>IMPACT cunoa\u0219te companiile, iar companiile ne cunosc pe noi. Pute\u021bi alege dintr-o gam\u0103 larg\u0103 de companii solide, din toat\u0103 Belgia.<\/p>\n\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \tContracte flexibile\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>Dori\u021bi s\u0103 experimenta\u021bi un nou loc de munc\u0103 sau un nou sector? S\u0103 trece\u021bi o anumit\u0103 perioad\u0103 de timp? Cu contractul dvs. temporar, pute\u021bi face acest lucru \u00een calitate de interimar f\u0103r\u0103 nicio problem\u0103.<\/p>\n\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \tPu\u021bine dureri de cap\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>Tu \u00ee\u021bi faci treaba, noi facem restul: plata \u0219i administrarea sunt aranjate s\u0103pt\u0103m\u00e2nal de IMPACT \u0219i de compania \u00een care lucrezi ca angajat temporar.<\/p>\n\n        <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_color=&#8221;bg_green&#8221; css=&#8221;.vc_custom_1758545212642{background-color: bg_green !important;}&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;5\/12&#8243;]\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-white\n            \">\n\t\t\t\t\n            \t... cu acelea\u0219i beneficii\n\t\t\t<\/h2>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-white\n        \">\n        \t\n            <p>Ca lucr\u0103tor temporar, ave\u021bi acela\u0219i statut social \u0219i acelea\u0219i condi\u021bii ca \u0219i angaja\u021bii permanen\u021bi. Diferen\u021ba? Contractul dvs. are o durat\u0103 determinat\u0103.<\/p>\n<p>Cu toate acestea, ave\u021bi dreptul la un salariu echivalent, presta\u021bii pentru copii, contribu\u021bii suplimentare, o prim\u0103 de sf\u00e2r\u0219it de an, s\u0103rb\u0103tori legale, asigurare pentru accidente de munc\u0103 etc.<\/p>\n\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-background button-size-normal background-color-fluent_yellow mobile_marginbottom-30px\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/impact.be\/ro\/candidati\/toate-posturile-vacante\/\" title=\"Descoper\u0103 toate locurile de munc\u0103\">\n                <div class=\"button-content\">\n                    <span>Descoper\u0103 toate locurile de munc\u0103<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\n        <div class=\"sd-block-image image-count-1  align-Left marginbottom-60px\n        \"><img decoding=\"async\" title=\"\" alt=\"\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/Met_dezelfde_voordelen.jpg\">\n        <\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-white\n            \">\n\t\t\t\t\n            \tSalarii \u0219i beneficii\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-white\n        \">\n        \t\n            <p>Ve\u021bi c\u00e2\u0219tiga acela\u0219i salariu ca un angajat cu aceea\u0219i pozi\u021bie \u0219i experien\u021b\u0103 \u00een aceea\u0219i companie. Acest lucru include avantaje precum tichetele de mas\u0103.<\/p>\n\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-white\n            \">\n\t\t\t\t\n            \tBani de vacan\u021b\u0103\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-white\n        \">\n        \t\n            <p>\u00cen calitate de lucr\u0103tor temporar, primi\u021bi cu siguran\u021b\u0103 indemniza\u021bie de concediu, doar c\u0103 momentul pl\u0103\u021bii variaz\u0103. Pute\u021bi conta at\u00e2t pe plata unic\u0103, c\u00e2t \u0219i pe plata dubl\u0103 a concediului.<\/p>\n\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-white\n            \">\n\t\t\t\t\n            \tVechime \u0219i pensionare\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-white\n        \">\n        \t\n            <p>Nu intra\u021bi \u00een panic\u0103: \u00een calitate de lucr\u0103tor temporar, acumula\u021bi vechime \u0219i beneficii de pensie. Toate serviciile pe care le furniza\u021bi \u00een calitate de lucr\u0103tor temporar sunt luate \u00een calcul.<\/p>\n\n        <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\n        <div class=\"sd-block-image image-count-1  align-Left marginbottom-60px\n        \"><img decoding=\"async\" title=\"\" alt=\"\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/En_ticket_richting.jpg\">\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;]\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \t... \u0219i bilet c\u0103tre un loc de munc\u0103 permanent\n\t\t\t<\/h2>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>Vremurile \u00een care, \u00een calitate de interimar, aveai pu\u021bine \u0219anse de a ob\u021bine un loc de munc\u0103 permanent sunt cu mult \u00een urm\u0103. \u00cen timpul perioadei de interimat, descoperi\u021bi dac\u0103 oamenii \u0219i cultura se potrivesc cu nevoile \u0219i caracterul dumneavoastr\u0103.<\/p>\n<p>Acest lucru v\u0103 ofer\u0103 o \u0219ans\u0103 de a st\u0103p\u00e2ni munca \u0219i de a demonstra c\u0103 sunte\u021bi un atu.<\/p>\n\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-background button-size-normal background-color-green mobile_marginbottom-30px\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/impact.be\/ro\/candidati\/toate-posturile-vacante\/\" title=\"Descoper\u0103 toate locurile de munc\u0103\">\n                <div class=\"button-content\">\n                    <span>Descoper\u0103 toate locurile de munc\u0103<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \tOportunitate pentru un contract permanent\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>O perioad\u0103 interimar\u0103 de succes? Asta v\u0103 ofer\u0103 70% \u0219anse de a ob\u021bine un contract permanent bine meritat.<\/p>\n\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \tDegetul pe puls\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>Felicit\u0103ri pentru contractul t\u0103u permanent! Dar IMPACT nu te va uita \u0219i ar dori s\u0103 \u021bin\u0103 leg\u0103tura cu tine pentru a afla cum merg lucrurile.<\/p>\n\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray\n            \">\n\t\t\t\t\n            \tGhid \u00een cariera ta\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>Via\u021ba ta este alc\u0103tuit\u0103 din mai multe capitole; la fel \u0219i cariera ta. Noi v\u0103 ajut\u0103m \u00een fiecare etap\u0103 a carierei dumneavoastr\u0103 profesionale.<\/p>\n\n        <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_color=&#8221;bg_gray&#8221;][vc_column]\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-center color-white\n            \">\n\t\t\t\t\n            \tSpeciali\u0219ti califica\u021bi la fel ca tine\n\t\t\t<\/h2>\n        <\/div>[vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\n        <div class=\"sd-block-text  marginbottom-30px color-white\n        \">\n        \t\n            <p style=\"text-align: center;\">L\u0103sa\u021bi-v\u0103 inspira\u021bi de pove\u0219tile altor exper\u021bi care \u0219i-au construit cariere \u00een domeniul construc\u021biilor, tehnic \u0219i \u00een alte sectoare prin intermediul IMPACT.<\/p>\n\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner]\n        <div class=\"sd-testimonial-slider candidates marginbottom-30px\">\n            <navigation class=\"nav-buttons\">\n                <div class=\"button button-prev\"><span><svg viewBox=\"0 0 12.5 11.2\" xml:space=\"preserve\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12.5,6.6H2.8l3.4,4.7H4L0,5.6L4,0h2.2L2.8,4.7h9.7V6.6z\" fill=\"currentColor\" \/><\/svg><\/span><\/div>\n                <div class=\"button button-next\"><span><svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg><\/span><\/div>\n            <\/navigation>\n            <div class=\"slider-inner-row\" data-itemsInView=\"1\">\n                            <div id=\"slide0\" class=\"slide\" data-slide=\"0\">\n                                <div class=\"slide-content\">\n                                    <div class=\"testimonial-image\"><img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/11\/Marek-Trojanowski.jpg\" alt=\"Marek Trojanowski\"><\/div>\n                            \n                                    <div class=\"testimonial-author\">\n                                        <div class=\"testimonial-author-name\"><span>Marek Trojanowski<\/span><\/div>\n                                        <div class=\"testimonial-author-function\"><span>vopsitor de mobil\u0103<\/span><\/div>\n                                    <\/div>\n                                    <div class=\"testimonial-quote\">\n                                        <div class=\"testimonial-quote-category\">Kandidaten aan het woord<\/div>\n                                        <div class=\"quote\">\n                                            \n                                            \n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-white font-middle\n            \">\n\t\t\t\t\n            \tDescoperi\u021bi cum a optat Marek pentru primul s\u0103u job ca lucr\u0103tor temporar.\n\t\t\t<\/h2>\n        <\/div>\n                                        <\/div>\n                                        <div class=\"testimonial-quote-controls\">\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-background button-size-small background-color-fluent_yellow\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/impact.be\/ro\/candida\u021bi\/testimonials\/marek-trojanowski\/\" title=\"Afl\u0103 mai multe\">\n                <div class=\"button-content\">\n                    <span>Afl\u0103 mai multe<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n                                            <div class=\"testimonial-quote-logo\">\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div id=\"slide1\" class=\"slide\" data-slide=\"1\">\n                                <div class=\"slide-content\">\n                                    <div class=\"testimonial-image\"><img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/09\/Melan.jpg\" alt=\"M\u00e9lan Chaspierre\"><\/div>\n                            \n                                    <div class=\"testimonial-author\">\n                                        <div class=\"testimonial-author-name\"><span>M\u00e9lan Chaspierre<\/span><\/div>\n                                        <div class=\"testimonial-author-function\"><span>Electrician<\/span><\/div>\n                                    <\/div>\n                                    <div class=\"testimonial-quote\">\n                                        <div class=\"testimonial-quote-category\">Kandidaten aan het woord<\/div>\n                                        <div class=\"quote\">\n                                            \n                                            \n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-white font-middle\n            \">\n\t\t\t\t\n            \tDescoperi\u021bi cum a g\u0103sit M\u00e9lan o solu\u021bie adecvat\u0103 atunci c\u00e2nd industria muzical\u0103 era \u00een impas\n\t\t\t<\/h2>\n        <\/div>\n                                        <\/div>\n                                        <div class=\"testimonial-quote-controls\">\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-background button-size-small background-color-fluent_yellow\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/impact.be\/ro\/candida\u021bi\/testimonials\/melan-chaspierre\/\" title=\"Afl\u0103 mai multe\">\n                <div class=\"button-content\">\n                    <span>Afl\u0103 mai multe<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n                                            <div class=\"testimonial-quote-logo\">\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div id=\"slide2\" class=\"slide\" data-slide=\"2\">\n                                <div class=\"slide-content\">\n                                    <div class=\"testimonial-image\"><img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/09\/Emilien.jpg\" alt=\"Emilien Catherine\"><\/div>\n                            \n                                    <div class=\"testimonial-author\">\n                                        <div class=\"testimonial-author-name\"><span>Emilien Catherine<\/span><\/div>\n                                        <div class=\"testimonial-author-function\"><span>Mecanic<\/span><\/div>\n                                    <\/div>\n                                    <div class=\"testimonial-quote\">\n                                        <div class=\"testimonial-quote-category\">Kandidaten aan het woord<\/div>\n                                        <div class=\"quote\">\n                                            \n                                            \n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-white font-middle\n            \">\n\t\t\t\t\n            \tAfla\u021bi cum a reu\u0219it Emilien s\u0103 semneze un contract permanent dup\u0103 un an.\n\t\t\t<\/h2>\n        <\/div>\n                                        <\/div>\n                                        <div class=\"testimonial-quote-controls\">\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-background button-size-small background-color-fluent_yellow\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/impact.be\/ro\/candida\u021bi\/testimonials\/emilien-catherine\/\" title=\"Afl\u0103 mai multe\">\n                <div class=\"button-content\">\n                    <span>Afl\u0103 mai multe<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n                                            <div class=\"testimonial-quote-logo\">\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <navigation class=\"navigation-bar\">\n                                    <div class=\"item item-0\" data-slide=\"0\">\n                                        <span>Marek - vopsitor de mobil\u0103<\/span>\n                                    <\/div>\n                                    <div class=\"item item-1\" data-slide=\"1\">\n                                        <span>M\u00e9lan - Electrician<\/span>\n                                    <\/div>\n                                    <div class=\"item item-2\" data-slide=\"2\">\n                                        <span>Emilien - Mecanic<\/span>\n                                    <\/div>\n                        <\/navigation>\n                <\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;color&#8221; bg_custom_color=&#8221;white&#8221; bg_color=&#8221;bg_green&#8221; css=&#8221;.vc_custom_1759405842414{background-color: bg_green !important;}&#8221;][vc_column width=&#8221;2\/12&#8243;][\/vc_column][vc_column width=&#8221;4\/12&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-white\n            \">\n\t\t\t\t\n            \tP\u0103stra\u021bi imaginea de ansamblu\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-white list-check\n        \">\n        \t\n            <p>Cu un profil My IMPACT, ave\u021bi o mul\u021bime de beneficii \u00eentr-un singur loc:<\/p>\n<ul class=\"checks\">\n<li>Vizualiza\u021bi aplica\u021biile dvs.<\/li>\n<li>Gestiona\u021bi alertele de locuri de munc\u0103 \u0219i CV-ul dvs.<\/li>\n<li>Actualiza\u021bi-v\u0103 informa\u021biile personale<\/li>\n<\/ul>\n\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-30px button-type-background button-size-normal background-color-fluent_yellow\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/portal.impact.be\/kandidatenportal\/registreer?lang=en\" target=\"_blank\" title=\"Creeaz\u0103-\u021bi profilul\">\n                <div class=\"button-content\">\n                    <span>Creeaz\u0103-\u021bi profilul<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>[\/vc_column][vc_column width=&#8221;4\/12&#8243;]\n        <div class=\"sd-block-image image-count-1  align-Left marginbottom-30px\n        \"><img decoding=\"async\" title=\"\" alt=\"\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/Bewaar_het_overzicht.png\">\n        <\/div>[\/vc_column][vc_column width=&#8221;2\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_color=&#8221;bg_gray&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243; responsive_marginbottom=&#8221;30px&#8221;]\n                <a class=\"sd-block-cta  marginbottom-0px mobile_marginbottom-30px\" title=\"C\u0103uta\u021bi un loc de munc\u0103 provocator \u00een construc\u021bii, tehnic\u0103, produc\u021bie sau logistic\u0103?\" href=\"https:\/\/impact.be\/ro\/candidati\/toate-posturile-vacante\/\"\n                >\n                    <div class=\"cta-inner\">\n                    \t<img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/Op_zoek_naar.jpg\" alt=\"\">\n                        <div class=\"sd-block-cta-title\">\n                            \n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-center color-white\n            \">\n\t\t\t\t\n            \tC\u0103uta\u021bi un loc de munc\u0103 provocator \u00een construc\u021bii, tehnic\u0103, produc\u021bie sau logistic\u0103?\n\t\t\t<\/h3>\n        <\/div>\n                        <\/div>\n                        <div class=\"sd-block-cta-text\">\n                        \t\n        <div class=\"sd-block-text  marginbottom-30px color-white\n        \">\n        \t\n            \n        <\/div>\n                        <\/div>\n                        <div class=\"sd-block-cta-button\">\n                        \t\n        <div class=\"sd-block-button  marginbottom-0px align-center button-type-background button-size-normal background-color-green\">\n            <span class=\"inner-button\"\n            href=\"\" title=\"Descoperi\u021bi posturile vacante\">\n                <div class=\"button-content\">\n                    <span>Descoperi\u021bi posturile vacante<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/span>\n        <\/div>\n                        <\/div>\n                    <\/div>\n                <\/a>[\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;]\n                <a class=\"sd-block-cta  marginbottom-0px\" title=\"A\u021bi prefera s\u0103 l\u0103sa\u021bi IMPACT s\u0103 v\u0103 g\u0103seasc\u0103 un loc de munc\u0103 potrivit?\" href=\"https:\/\/impact.be\/ro\/candidati\/aplicare-spontana\/\"\n                >\n                    <div class=\"cta-inner\">\n                    \t<img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/Laat_je_impact.jpg\" alt=\"\">\n                        <div class=\"sd-block-cta-title\">\n                            \n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-center color-white\n            \">\n\t\t\t\t\n            \tA\u021bi prefera s\u0103 l\u0103sa\u021bi IMPACT s\u0103 v\u0103 g\u0103seasc\u0103 un loc de munc\u0103 potrivit?\n\t\t\t<\/h3>\n        <\/div>\n                        <\/div>\n                        <div class=\"sd-block-cta-text\">\n                        \t\n        <div class=\"sd-block-text  marginbottom-30px color-white\n        \">\n        \t\n            \n        <\/div>\n                        <\/div>\n                        <div class=\"sd-block-cta-button\">\n                        \t\n        <div class=\"sd-block-button  marginbottom-0px align-center button-type-background button-size-normal background-color-green\">\n            <span class=\"inner-button\"\n            href=\"\" title=\"Aplica\u021bi spontan\">\n                <div class=\"button-content\">\n                    <span>Aplica\u021bi spontan<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/span>\n        <\/div>\n                        <\/div>\n                    <\/div>\n                <\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;bottom&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;image&#8221; row_height=&#8221;row_900px&#8221; bg_color=&#8221;bg_gray&#8221; bg_custom_img=&#8221;1942&#8243; css=&#8221;.vc_custom_1759405268187{background-color: bg_gray !important;}&#8221;][vc_column width=&#8221;2\/5&#8243;][\/vc_column][vc_column width=&#8221;3\/5&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_color=&#8221;bg_green&#8221; css=&#8221;.vc_custom_1758545212642{background-color: bg_green !important;}&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_color=&#8221;bg_gray&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;color&#8221; bg_custom_color=&#8221;white&#8221; bg_color=&#8221;bg_green&#8221; css=&#8221;.vc_custom_1759405842414{background-color: bg_green !important;}&#8221;][vc_column width=&#8221;2\/12&#8243;][\/vc_column][vc_column &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/impact.be\/ro\/candida\u021bi\/testimonials\/emilien-catherine\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8222;Emilien Catherine&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5190,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9826","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lucru temporar | IMPACT<\/title>\n<meta name=\"description\" content=\"\u00cen calitate de angajat temporar, ave\u021bi dreptul la acelea\u0219i beneficii \u0219i salarii ca un angajat permanent. Descoperi\u021bi beneficiile \u0219i modul \u00een care IMPACT v\u0103 sprijin\u0103 pe deplin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lucru temporar | IMPACT\" \/>\n<meta property=\"og:description\" content=\"\u00cen calitate de angajat temporar, ave\u021bi dreptul la acelea\u0219i beneficii \u0219i salarii ca un angajat permanent. Descoperi\u021bi beneficiile \u0219i modul \u00een care IMPACT v\u0103 sprijin\u0103 pe deplin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/\" \/>\n<meta property=\"og:site_name\" content=\"IMPACT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jobs.impact\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T17:30:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/11\/Social-share.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucru-temporar\\\/\",\"url\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucru-temporar\\\/\",\"name\":\"Lucru temporar | IMPACT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/#website\"},\"datePublished\":\"2025-08-15T12:31:39+00:00\",\"dateModified\":\"2025-11-14T17:30:42+00:00\",\"description\":\"\u00cen calitate de angajat temporar, ave\u021bi dreptul la acelea\u0219i beneficii \u0219i salarii ca un angajat permanent. Descoperi\u021bi beneficiile \u0219i modul \u00een care IMPACT v\u0103 sprijin\u0103 pe deplin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucru-temporar\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucru-temporar\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucru-temporar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/impact.be\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candida\u021bi\",\"item\":\"https:\\\/\\\/impact.be\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lucru temporar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/impact.be\\\/ro\\\/\",\"name\":\"IMPACT\",\"description\":\"Impact website\",\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lucru temporar | IMPACT","description":"\u00cen calitate de angajat temporar, ave\u021bi dreptul la acelea\u0219i beneficii \u0219i salarii ca un angajat permanent. Descoperi\u021bi beneficiile \u0219i modul \u00een care IMPACT v\u0103 sprijin\u0103 pe deplin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/","og_locale":"ro_RO","og_type":"article","og_title":"Lucru temporar | IMPACT","og_description":"\u00cen calitate de angajat temporar, ave\u021bi dreptul la acelea\u0219i beneficii \u0219i salarii ca un angajat permanent. Descoperi\u021bi beneficiile \u0219i modul \u00een care IMPACT v\u0103 sprijin\u0103 pe deplin.","og_url":"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/","og_site_name":"IMPACT","article_publisher":"https:\/\/www.facebook.com\/jobs.impact","article_modified_time":"2025-11-14T17:30:42+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/impact.be\/wp-content\/uploads\/2025\/11\/Social-share.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"5 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/","url":"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/","name":"Lucru temporar | IMPACT","isPartOf":{"@id":"https:\/\/impact.be\/ro\/#website"},"datePublished":"2025-08-15T12:31:39+00:00","dateModified":"2025-11-14T17:30:42+00:00","description":"\u00cen calitate de angajat temporar, ave\u021bi dreptul la acelea\u0219i beneficii \u0219i salarii ca un angajat permanent. Descoperi\u021bi beneficiile \u0219i modul \u00een care IMPACT v\u0103 sprijin\u0103 pe deplin.","breadcrumb":{"@id":"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/impact.be\/ro\/candidati\/lucru-temporar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/impact.be\/ro\/"},{"@type":"ListItem","position":2,"name":"Candida\u021bi","item":"https:\/\/impact.be\/ro\/"},{"@type":"ListItem","position":3,"name":"Lucru temporar"}]},{"@type":"WebSite","@id":"https:\/\/impact.be\/ro\/#website","url":"https:\/\/impact.be\/ro\/","name":"IMPACT","description":"Impact website","inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/9826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/comments?post=9826"}],"version-history":[{"count":5,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/9826\/revisions"}],"predecessor-version":[{"id":12799,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/9826\/revisions\/12799"}],"up":[{"embeddable":true,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/5190"}],"wp:attachment":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/media?parent=9826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}