{"id":11045,"date":"2025-10-07T10:59:21","date_gmt":"2025-10-07T08:59:21","guid":{"rendered":"https:\/\/impact.be\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/"},"modified":"2025-12-18T12:10:38","modified_gmt":"2025-12-18T11:10:38","slug":"logistica-locuri-de-munca-in-limburg","status":"publish","type":"page","link":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/","title":{"rendered":"Logistic\u0103 locuri de munc\u0103 \u00een Limburg"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;bottom&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;image&#8221; row_height=&#8221;row_500px&#8221; bg_color=&#8221;bg_gray&#8221; css=&#8221;.vc_custom_1757059736611{background-color: bg_green !important;}&#8221; bg_custom_img=&#8221;202&#8243;][vc_column width=&#8221;2\/5&#8243;]\n        <div class=\"sd-block-breadcrumb  align-left color-white marginbottom-30px\n        \">\n            <ul id=\"breadcrumbs\" class=\"breadcrumbs\"><\/ul>\n        <\/div>\n        <div class=\"sd-block-title \">\n            <h1 class=\"sd-block-title-htag  marginbottom-0px align-left color-white has-bracket\n            \">\n\t\t\t\t<span class=\"bracket-icon bracket-green\"><svg viewBox=\"0 0 165.66 193.66\" width=\"15px\" height=\"15px\" preserveAspectRatio=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><polygon fill=\"currentColor\" points=\"46.75 168.35 125.45 25.31 151.73 25.31 165.66 0 106.55 0 0 193.66 59.11 193.66 73.04 168.35 46.75 168.35\" \/><\/svg><\/span>\n            \tLocuri de munc\u0103 \u00een logistic\u0103 \u0219i transport \u00een Limburg\n\t\t\t<\/h1>\n        <\/div>[\/vc_column][vc_column width=&#8221;3\/5&#8243;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_class=&#8221;row-vacancy row-scrollable&#8221;][vc_column width=&#8221;5\/12&#8243; el_class=&#8221;vacancy-overview-column&#8221;]\n             <div id=\"filter-anchor\" class=\"sd-custom-post-type-filters  basic\">\n                <form action=\"\" method=\"get\" data-shortcode=\"sd_block_job_overview\" data-target_div=\".sd-block-job-overview\"><div class=\"reset-filter-container\"><svg width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 16\"><path fill=\"currentColor\" d=\"M8,16c-2.2,0-4.1-0.8-5.7-2.3S0,10.2,0,8s0.8-4.1,2.3-5.7S5.8,0,8,0c1.2,0,2.2,0.2,3.3,0.7s1.9,1.2,2.7,2V0h2v7 H9V5h4.2c-0.5-0.9-1.3-1.7-2.2-2.2C10.1,2.3,9.1,2,8,2C6.3,2,4.9,2.6,3.8,3.8S2,6.3,2,8s0.6,3.1,1.8,4.2S6.3,14,8,14 c1.3,0,2.4-0.4,3.5-1.1c1-0.7,1.8-1.7,2.2-2.9h2.1c-0.5,1.8-1.4,3.2-2.8,4.3S9.8,16,8,16z\"\/><\/svg><input class=\"reset-filter\" type=\"reset\" value=\"Reseta\u021bi filtrul\"><\/div>\n                        <input type=\"hidden\" name=\"post_type\" value=\"job\">\n                        <input type=\"hidden\" name=\"filter_type\" value=\"basic\"><input type=\"hidden\" name=\"language\" value=\"ro\">\n                        <div class=\"vc_col-md-12\" style=\"float: none; margin-left: auto; margin-right: auto;\">\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-text \">\n                                <div class=\"sd-custom-post-type-filter-input\"><input type=\"text\" autocomplete=\"off\"  placeholder=\"Ce c\u0103uta\u021bi?\" name=\"keyword\" value=\"\"><div class=\"sd-custom-post-type-filter-autocomplete\"><\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-distance \">\n                                <div class=\"sd-custom-post-type-filter-input\"><input type=\"text\" placeholder=\"Ora\u0219 sau cod po\u0219tal\" name=\"cptf_location\" value=\"\">\n        <select name=\"cptf_distance\" data-default=\"10\">\n            <option value=\"\">Distan\u021b\u0103<\/option><option value=\"10\" selected>\u2264 10 km<\/option><option value=\"15\" >\u2264 15 km<\/option><option value=\"20\" >\u2264 20 km<\/option><option value=\"25\" >\u2264 25 km<\/option><option value=\"30\" >\u2264 30 km<\/option><option value=\"50\" >\u2264 50 km<\/option><option value=\"100\" >\u2264 100 km<\/option>\n        <\/select>\n                                <\/div>\n                            <\/div><div class=\"advanced_filter_wrapper\">\n                                    <div class=\"advanced_filter_inner_wrapper\">\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-checkbox sd-hidden\">\n                                <div class=\"sd-custom-post-type-filter-input\">\n            <div class=\"checkbox-trigger-container\">\n            <div class=\"checkbox-trigger\" data-placeholder-text=\"Sector\" data-count=\"\">\n                <span><svg viewBox=\"0 0 15 15\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.4,2.3c0,1.3-1,2.3-2.3,2.3c-1.2,0-2.3-1-2.3-2.3C1,1,1.9,0,3.1,0S5.4,1,5.4,2.3z M5.5,5.9C4.7,6.4,4.1,7.2,3.8,8.3H0V7.6 \tc0-1.3,1-2.3,2.2-2.3H4C4.7,5.3,5,5.5,5.5,5.9z M14,2.3c0,1.3-1,2.3-2.3,2.3S9.6,3.5,9.6,2.3C9.6,1,10.7,0,11.9,0S14,1,14,2.3z \t M15,7.6v0.7h-3.7c-0.2-1-0.8-1.9-1.7-2.4c0.4-0.4,0.8-0.5,1.3-0.5h1.8C14,5.3,15,6.4,15,7.6z M9.7,9c0,1.3-1,2.3-2.3,2.3 \tc-1.2,0-2.2-1.1-2.2-2.3c0-0.2,0.1-0.5,0.1-0.7c0.1-0.5,0.5-0.8,0.8-1.1s0.8-0.4,1.2-0.4c0.5,0,1,0.1,1.2,0.4c0.6,0.2,0.8,0.6,1,1.1 \tC9.7,8.5,9.7,8.8,9.7,9z M10.7,14.3V15H4.3v-0.7c0-1,0.5-1.7,1.2-2c0.4-0.1,0.7-0.2,1-0.2h1.9c0.4,0,0.7,0.1,1,0.2 \tC10.2,12.7,10.7,13.4,10.7,14.3z\" fill=\"currentColor\" \/><\/svg>Sector<\/span>\n            <\/div>\n            <div class=\"checkbox-options\">\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel1[]\" id=\"8407\" value=\"8407\"  >\n                <label for=\"8407\">Construc\u021bie<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel1[]\" id=\"8409\" value=\"8409\"  >\n                <label for=\"8409\">Produc\u021bie<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel1[]\" id=\"8410\" value=\"8410\"  >\n                <label for=\"8410\">Tehnic\u0103<\/label>\n            <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-checkbox \">\n                                <div class=\"sd-custom-post-type-filter-input\">\n            <div class=\"checkbox-trigger-container\">\n            <div class=\"checkbox-trigger\" data-placeholder-text=\"Domeniu func\u021bie\" data-count=\"\">\n                <span><svg viewBox=\"0 0 15 15\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.4,2.3c0,1.3-1,2.3-2.3,2.3c-1.2,0-2.3-1-2.3-2.3C1,1,1.9,0,3.1,0S5.4,1,5.4,2.3z M5.5,5.9C4.7,6.4,4.1,7.2,3.8,8.3H0V7.6 \tc0-1.3,1-2.3,2.2-2.3H4C4.7,5.3,5,5.5,5.5,5.9z M14,2.3c0,1.3-1,2.3-2.3,2.3S9.6,3.5,9.6,2.3C9.6,1,10.7,0,11.9,0S14,1,14,2.3z \t M15,7.6v0.7h-3.7c-0.2-1-0.8-1.9-1.7-2.4c0.4-0.4,0.8-0.5,1.3-0.5h1.8C14,5.3,15,6.4,15,7.6z M9.7,9c0,1.3-1,2.3-2.3,2.3 \tc-1.2,0-2.2-1.1-2.2-2.3c0-0.2,0.1-0.5,0.1-0.7c0.1-0.5,0.5-0.8,0.8-1.1s0.8-0.4,1.2-0.4c0.5,0,1,0.1,1.2,0.4c0.6,0.2,0.8,0.6,1,1.1 \tC9.7,8.5,9.7,8.8,9.7,9z M10.7,14.3V15H4.3v-0.7c0-1,0.5-1.7,1.2-2c0.4-0.1,0.7-0.2,1-0.2h1.9c0.4,0,0.7,0.1,1,0.2 \tC10.2,12.7,10.7,13.4,10.7,14.3z\" fill=\"currentColor\" \/><\/svg>Domeniu func\u021bie<\/span>\n            <\/div>\n            <div class=\"checkbox-options\">\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8416\" value=\"8416\"  >\n                <label for=\"8416\">Asamblare \u0219i montare<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8417\" value=\"8417\"  >\n                <label for=\"8417\">Automobil<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8418\" value=\"8418\"  >\n                <label for=\"8418\">Beton<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8421\" value=\"8421\"  >\n                <label for=\"8421\">Electricitate<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8424\" value=\"8424\"  >\n                <label for=\"8424\">Facilit\u0103\u021bi \u0219i \u00eentre\u021binere<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8429\" value=\"8429\"  >\n                <label for=\"8429\">HVAC \u0219i r\u0103cire<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8447\" value=\"8447\"  >\n                <label for=\"8447\">Lucr\u0103ri de produc\u021bie<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8439\" value=\"8439\"  >\n                <label for=\"8439\">Mecanic\u0103<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8440\" value=\"8440\"  >\n                <label for=\"8440\">Metal<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8443\" value=\"8443\"  >\n                <label for=\"8443\">Operator (ma\u0219in\u0103\/linie\/proces)<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8446\" value=\"8446\"  >\n                <label for=\"8446\">Produc\u021bie \u0219i \u00eentre\u021binere<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toBrancheLevel2[]\" id=\"8451\" value=\"8451\"  >\n                <label for=\"8451\">T\u00e2mpl\u0103rie<\/label>\n            <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-checkbox \">\n                                <div class=\"sd-custom-post-type-filter-input\">\n            <div class=\"checkbox-trigger-container\">\n            <div class=\"checkbox-trigger\" data-placeholder-text=\"Func\u021bie\" data-count=\"\">\n                <span><svg viewBox=\"0 0 12.6 11.9\" xml:space=\"preserve\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.9,2.6V0H2.7v2.6H0v9.2h12.6V2.6H9.9z M4.2,1.5h4.3v1.2H4.2V1.5z M11.1,10.4H1.5V4.1h9.6V10.4z\" fill=\"currentColor\" \/><\/svg>Func\u021bie<\/span>\n            <\/div>\n            <div class=\"checkbox-options\">\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"6894\" value=\"6894\"  >\n                <label for=\"6894\">Ajut\u0103tor Construc\u021bii<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"6877\" value=\"6877\"  >\n                <label for=\"6877\">Dulgher<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7211\" value=\"7211\"  >\n                <label for=\"7211\">Electromecanic<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"6960\" value=\"6960\"  >\n                <label for=\"6960\">Gr\u0103dinar<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"6892\" value=\"6892\"  >\n                <label for=\"6892\">Lucr\u0103tor beton<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7224\" value=\"7224\"  >\n                <label for=\"7224\">Mecanic<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7281\" value=\"7281\"  >\n                <label for=\"7281\">Mecanic<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7429\" value=\"7429\"  >\n                <label for=\"7429\">Mecanic de camion<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7279\" value=\"7279\"  >\n                <label for=\"7279\">Mecanic de \u00eentre\u021binere<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7009\" value=\"7009\"  >\n                <label for=\"7009\">Muncitor prelucrare piatr\u0103<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7153\" value=\"7153\"  >\n                <label for=\"7153\">Operator CNC<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7272\" value=\"7272\"  >\n                <label for=\"7272\">Operator ma\u0219in\u0103<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7313\" value=\"7313\"  >\n                <label for=\"7313\">Preparator vopsire caroserii<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7349\" value=\"7349\"  >\n                <label for=\"7349\">Preparator\/planificator de lucru<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7154\" value=\"7154\"  >\n                <label for=\"7154\">Programator CNC<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7440\" value=\"7440\"  >\n                <label for=\"7440\">Sudor<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7236\" value=\"7236\"  >\n                <label for=\"7236\">Tehnician HVAC<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7672\" value=\"7672\"  >\n                <label for=\"7672\">Tinichigiu<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7398\" value=\"7398\"  >\n                <label for=\"7398\">Vopsitor industrial cu pistol<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toFunctionLevel2[]\" id=\"7004\" value=\"7004\"  >\n                <label for=\"7004\">Zidar<\/label>\n            <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-checkbox \">\n                                <div class=\"sd-custom-post-type-filter-input\">\n            <div class=\"checkbox-trigger-container\">\n            <div class=\"checkbox-trigger\" data-placeholder-text=\"Regiune\" data-count=\"\">\n                <span><svg viewBox=\"0 0 10 12.5\" xml:space=\"preserve\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8.5,1.5c-2-2-5.1-2-7.1,0c-2,2-2,5.3,0,7.3L5,12.5l3.5-3.7C10.5,6.8,10.5,3.5,8.5,1.5z M5,6.2c-0.6,0-1.1-0.5-1.1-1.1 \tc0-0.6,0.5-1.1,1.1-1.1c0.6,0,1.1,0.5,1.1,1.1C6.1,5.8,5.6,6.2,5,6.2z\" fill=\"currentColor\" \/><\/svg>Regiune<\/span>\n            <\/div>\n            <div class=\"checkbox-options\">\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toProvince1Node[]\" id=\"4072\" value=\"4072\"  >\n                <label for=\"4072\">Bruxelles<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toProvince1Node[]\" id=\"4081\" value=\"4081\"  >\n                <label for=\"4081\">Flandra de Vest<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"toProvince1Node[]\" id=\"4074\" value=\"4074\" checked=\"checked\" >\n                <label for=\"4074\">Limburg<\/label>\n            <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-checkbox \">\n                                <div class=\"sd-custom-post-type-filter-input\">\n            <div class=\"checkbox-trigger-container\">\n            <div class=\"checkbox-trigger\" data-placeholder-text=\"Regim\" data-count=\"\">\n                <span><svg viewBox=\"0 0 12.5 12.5\" xml:space=\"preserve\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8.9,3.6C8.2,2.9,7.2,2.5,6.3,2.5v3.8L3.6,8.9c1.5,1.5,3.8,1.5,5.3,0C10.4,7.4,10.4,5.1,8.9,3.6z M6.3,0C2.8,0,0,2.8,0,6.2 \tc0,3.5,2.8,6.3,6.3,6.3c3.4,0,6.3-2.8,6.3-6.3C12.5,2.8,9.7,0,6.3,0L6.3,0z M6.3,11.2c-2.8,0-5-2.2-5-5c0-2.8,2.2-5,5-5 \tc2.8,0,5,2.2,5,5C11.2,9,9,11.2,6.3,11.2z\" fill=\"currentColor\" \/><\/svg>Regim<\/span>\n            <\/div>\n            <div class=\"checkbox-options\">\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"additionalInfo_7745[]\" id=\"7743\" value=\"7743\"  >\n                <label for=\"7743\">Norm\u0103 \u00eentreag\u0103<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"additionalInfo_7745[]\" id=\"7744\" value=\"7744\"  >\n                <label for=\"7744\">Timp par\u0163ial de munc\u0103 - 4 din 5 zile lucr\u0103toare<\/label>\n            <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"sd-custom-post-type-filter sd-custom-post-type-filter-type-checkbox \">\n                                <div class=\"sd-custom-post-type-filter-input\">\n            <div class=\"checkbox-trigger-container\">\n            <div class=\"checkbox-trigger\" data-placeholder-text=\"Schimburi\" data-count=\"\">\n                <span><svg viewBox=\"0 0 12.5 12.5\" xml:space=\"preserve\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M6.3,0C2.8,0,0,2.8,0,6.2c0,3.5,2.8,6.3,6.3,6.3c3.4,0,6.3-2.8,6.3-6.3C12.5,2.8,9.7,0,6.3,0z M5.6,11.2 \tc-2.5-0.3-4.4-2.4-4.4-5c0-2.5,1.9-4.6,4.4-5V11.2z M6.9,1.3c0.6,0.1,1.2,0.3,1.8,0.6H6.9V1.3z M6.9,3.1h3.3 \tc0.2,0.2,0.3,0.4,0.4,0.6H6.9V3.1z M6.9,5h4.2c0.1,0.2,0.1,0.4,0.1,0.6H6.9V5z M6.9,11.2v-0.6h1.8C8.1,10.9,7.5,11.1,6.9,11.2z \t M10.1,9.4H6.9V8.8h3.7C10.4,9,10.3,9.2,10.1,9.4z M11.1,7.5H6.9V6.9h4.3C11.2,7.1,11.1,7.3,11.1,7.5z\" fill=\"currentColor\" \/><\/svg>Schimburi<\/span>\n            <\/div>\n            <div class=\"checkbox-options\">\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"additionalInfo_7756[]\" id=\"7754\" value=\"7754\"  >\n                <label for=\"7754\">2-echipe<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"additionalInfo_7756[]\" id=\"7750\" value=\"7750\"  >\n                <label for=\"7750\">Serviciu de zi<\/label>\n            <\/div>\n            <div class=\"checkbox-container\">\n                <input type=\"checkbox\" name=\"additionalInfo_7756[]\" id=\"7747\" value=\"7747\"  >\n                <label for=\"7747\">Serviciul de diminea\u021b\u0103<\/label>\n            <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n                            <\/div><div class=\"close-button\"><div class=\"close-button-inner\">Afi\u0219eaz\u0103 locuri de munc\u0103<\/div><svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg><\/div><\/div><\/div><button type=\"button\" class=\"advanced-filter\">Filtru avansat<\/button>\n                        <\/div>\n                <\/form>\n            <\/div>\n        <div class=\"sd-block-job-overview\" data-atts=\"{&quot;posts_per_page&quot;:&quot;12&quot;,&quot;pagination&quot;:&quot;yes&quot;,&quot;title&quot;:&quot;Aplicare spontan\\u0103&quot;,&quot;text&quot;:&quot;Nu ai g\\u0103sit provocarea pe care \\u021bi-o dore\\u0219ti cu adev\\u0103rat? Aplic\\u0103 Spontaneously \\u0219i te vom contacta atunci c\\u00e2nd vom g\\u0103si un job potrivit pentru tine! &quot;,&quot;url&quot;:&quot;url:https%3A%2F%2Fimpact.be%2Fro%2Fcandidati%2Faplicare-spontana%2F|&quot;,&quot;button_text&quot;:&quot;Aplica\\u021bi spontan&quot;,&quot;bg_image&quot;:&quot;2956&quot;}\" data-page-id=\"1\" data-job-amount=\"0\">\n        <a class=\"job-no-results-container\" href=\"\/en\/candidates\/apply-spontaneously\">\n            <div class=\"inner-content\">\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-20px align-left color-white font-mini\n            \">\n\t\t\t\t\n            \tAplicare spontan\u0103\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-20px color-white\n        \">\n        \t\n            <p>Nu a\u021bi g\u0103sit provocarea pe care o c\u0103uta\u021bi cu adev\u0103rat? Aplica\u021bi spontan \u0219i v\u0103 vom contacta c\u00e2nd g\u0103sim jobul potrivit pentru dvs.!\"<\/p>\n\n        <\/div><\/div>\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-background button-size-small background-color-white\">\n            <span class=\"inner-button\"\n            href=\"\" title=\"Aplicare spontan\u0103\">\n                <div class=\"button-content\">\n                    <span>Aplicare spontan\u0103<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/span>\n        <\/div>\n        <\/a>\n        <\/div>[\/vc_column][vc_column width=&#8221;7\/12&#8243; el_class=&#8221;single-job custom-col-enable col-scrollable vacancy-single-column&#8221;][vc_row_inner row_inner_color=&#8221;white&#8221;][vc_column_inner]\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray font-middle\n            \">\n\t\t\t\t\n            \tLocuri de munc\u0103 \u00een logistic\u0103 \u0219i transport \u00een Limburg\n\t\t\t<\/h2>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark list-check\n        \">\n        \t\n            <p>\u00ce\u021bi place ac\u021biunea, planificarea sau condusul? <strong>IMPACT<\/strong> are <strong>locuri de munc\u0103 vacante<\/strong> \u00een <strong>logistic\u0103<\/strong> \u0219i <strong>transport<\/strong> \u00een <strong>Limburg<\/strong>, la diverse depozite, transportatori \u0219i centre de distribu\u021bie.<\/p>\n\n        <\/div>\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray font-middle\n            \">\n\t\t\t\t\n            \tC\u0103uta\u021bi un loc de munc\u0103 \u00een logistic\u0103 sau transport \u00een Limburg?\n\t\t\t<\/h2>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark\n        \">\n        \t\n            <p>\u00cen centrele <strong>logistice<\/strong> din Limburg, cum ar fi <strong>Hasselt<\/strong>, <strong>Genk<\/strong>, <strong>Pelt<\/strong>, <strong>Lommel<\/strong>, totul este despre eficien\u021b\u0103. <strong>IMPACT <\/strong>v\u0103 ajut\u0103 s\u0103 g\u0103si\u021bi un loc de munc\u0103 \u00een depozit, transport sau planificare, adaptat experien\u021bei dumneavoastr\u0103.<\/p>\n<p><strong>De ce s\u0103 alege\u021bi logistica \u0219i transportul:<\/strong><\/p>\n<ul>\n<li>Remunera\u021bie bun\u0103 cu beneficii suplimentare<\/li>\n<li>Func\u021bii variate: depozit, stivuitor, transport, dispecerat<\/li>\n<li>Lucru \u00een echip\u0103 \u00eentr-un mediu dinamic<\/li>\n<li>Siguran\u021ba locului de munc\u0103 \u00eentr-o industrie \u00een cre\u0219tere<\/li>\n<\/ul>\n\n        <\/div>\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray font-middle\n            \">\n\t\t\t\t\n            \tDe ce s\u0103 alege\u021bi un loc de munc\u0103 prin IMPACT:\n\t\t\t<\/h2>\n        <\/div>\n        <div class=\"sd-block-text  marginbottom-30px color-gray_dark list-check\n        \">\n        \t\n            <p>Recrutorii no\u0219tri cunosc <strong>companiile de<\/strong> <strong>logistic\u0103<\/strong> \u0219i <strong>transport<\/strong> din <strong>Limburg<\/strong> \u0219i \u0219tiu ce locuri de munc\u0103 se potrivesc perfect profilului t\u0103u.<\/p>\n\n        <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1761311432051{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column]\n            <div class=\"sd-apply-block collage\">\n                <div class=\"image image-1\">\n                    <img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/1.jpg\" alt=\"Vrachtwagenchauffeur\">\n                <\/div>\n                <sd-sdcx-vacancies-apply-open :publication-i-d=\"1\"><\/sd-sdcx-vacancies-apply-open>\n                <div class=\"image image-2\">\n                    <img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/2.jpg\" alt=\"Lasser\">\n                    <div class=\"specs\">\n                        <div class=\"spec\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10 11.2\" xml:space=\"preserve\" width=\"15px\" height=\"15px\">\n  <path d=\"M5.6,3.5c-0.5,0-0.9,0.4-0.9,0.9c0,0.5,0.4,0.9,0.9,0.9c0.5,0,0.9-0.4,0.9-0.9C6.5,3.9,6.1,3.5,5.6,3.5z\" fill=\"currentColor\"><\/path>\n  <path d=\"M5.6,0C3.3,0,1.4,1.8,1.3,4.2L0.1,5.7c-0.2,0.2,0,0.5,0.2,0.5h0.9v1.9c0,0.7,0.6,1.2,1.3,1.2h0.6v1.9h4.4V8.3 C9,7.6,10,6.1,10,4.4C10,2,8,0,5.6,0z M7.5,4.4c0,0.1,0,0.2,0,0.2L8,5c0,0,0.1,0.1,0,0.2L7.5,6.1c0,0.1-0.1,0.1-0.2,0.1L6.8,5.9 C6.6,6,6.5,6,6.4,6.1L6.3,6.8c0,0.1-0.1,0.1-0.1,0.1h-1C5.1,6.9,5,6.8,5,6.8L4.9,6.1C4.8,6,4.6,6,4.5,5.9L3.9,6.1 c-0.1,0-0.1,0-0.2-0.1L3.2,5.2c0,0,0-0.1,0-0.2l0.5-0.4c0-0.1,0-0.2,0-0.2c0-0.1,0-0.2,0-0.2L3.2,3.7c0,0-0.1-0.1,0-0.2l0.5-0.9 c0-0.1,0.1-0.1,0.1-0.1l0.6,0.3c0.1-0.1,0.3-0.2,0.4-0.2L5,2c0-0.1,0.1-0.1,0.1-0.1h1c0.1,0,0.1,0,0.1,0.1l0.1,0.7 c0.1,0.1,0.3,0.1,0.4,0.2l0.6-0.3c0.1,0,0.1,0,0.2,0.1L8,3.6c0,0.1,0,0.1,0,0.2L7.5,4.1C7.5,4.2,7.5,4.3,7.5,4.4z\" fill=\"currentColor\"><\/path>\n<\/svg>\n Ani de expertiz\u0103<\/div>    \n                        <div class=\"spec\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 15\" width=\"15px\" height=\"15px\">\n  <path d=\"M5.4,2.3c0,1.3-1,2.3-2.3,2.3c-1.2,0-2.3-1-2.3-2.3C1,1,1.9,0,3.1,0S5.4,1,5.4,2.3z M5.5,5.9C4.7,6.4,4.1,7.2,3.8,8.3H0V7.6 c0-1.3,1-2.3,2.2-2.3H4C4.7,5.3,5,5.5,5.5,5.9z M14,2.3c0,1.3-1,2.3-2.3,2.3S9.6,3.5,9.6,2.3C9.6,1,10.7,0,11.9,0S14,1,14,2.3z M15,7.6v0.7h-3.7c-0.2-1-0.8-1.9-1.7-2.4c0.4-0.4,0.8-0.5,1.3-0.5h1.8C14,5.3,15,6.4,15,7.6z M9.7,9c0,1.3-1,2.3-2.3,2.3 c-1.2,0-2.2-1.1-2.2-2.3c0-0.2,0.1-0.5,0.1-0.7c0.1-0.5,0.5-0.8,0.8-1.1s0.8-0.4,1.2-0.4c0.5,0,1,0.1,1.2,0.4c0.6,0.2,0.8,0.6,1,1.1 C9.7,8.5,9.7,8.8,9.7,9z M10.7,14.3V15H4.3v-0.7c0-1,0.5-1.7,1.2-2c0.4-0.1,0.7-0.2,1-0.2h1.9c0.4,0,0.7,0.1,1,0.2 C10.2,12.7,10.7,13.4,10.7,14.3z\" fill=\"currentColor\"><\/path>\n<\/svg>\n Re\u021bea extins\u0103<\/div>    \n                        <div class=\"spec\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14.3 12.5\" xml:space=\"preserve\" width=\"15px\" height=\"15px\">\n  <path d=\"M0,0v11.4h2.1L4.5,9h1.6c0.1-0.6,0.2-1.1,0.4-1.6H3.8L1.6,9.7V1.6h9v3c0.1,0,0.3,0,0.4,0c0.4,0,0.8,0.1,1.2,0.1V0.1L0,0L0,0 z M8.6,3.6h-5v1.6h5V3.6z M12.9,7.6V5.9h-4v1.7H7.6v4.9h6.7V7.6H12.9z M10.1,7.1h1.7v0.5h-1.7V7.1z M13.1,11.4H8.7V8.8h4.4V11.4z\" fill=\"currentColor\"><\/path>\n<\/svg>\n Proces simplu de aplicare<\/div>    \n                    <\/div>\n                <\/div>\n                <div class=\"image image-3\">\n                    [vc_widget_sidebar sidebar_id=\"google-reviews\"]\n                    <img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/3.jpg\" alt=\"Slijper\">\n                <\/div>\n                <div class=\"image image-4\">\n                    <img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/4.jpg\" alt=\"Spuiter\">\n                <\/div>\n                <div class=\"image image-5\">\n                    <img decoding=\"async\" src=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/10\/5.jpg\" alt=\"Stukadoor\">\n                <\/div>\n            <\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;10\/12&#8243;]\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-60px align-center color-dark_gray has-bracket\n            \">\n\t\t\t\t<span class=\"bracket-icon bracket-green\"><svg viewBox=\"0 0 165.66 193.66\" width=\"15px\" height=\"15px\" preserveAspectRatio=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><polygon fill=\"currentColor\" points=\"46.75 168.35 125.45 25.31 151.73 25.31 165.66 0 106.55 0 0 193.66 59.11 193.66 73.04 168.35 46.75 168.35\" \/><\/svg><\/span>\n            \t\u00cen 5 pa\u0219i c\u0103tre noul t\u0103u loc de munc\u0103\n\t\t\t<\/h2>\n        <\/div>\n         <div class=\"sd-method-slider slider-not-active marginbottom-30px\">            \n            <div class=\"background-line\"><\/div>\n            <div class=\"slider-inner-row\" data-itemsInView=\"5\" data-slideAmmount=\"5\">\n                            <div id=\"slide0\" class=\"slide\" data-slide=\"0\">\n                                <div class=\"slide-content\">\n                                \t<div class=\"slide-count\">1<\/div>\n                                \t<div class=\"content-container\">\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-blue font-mini\n            \">\n\t\t\t\t\n            \tAplica\u021bie\n\t\t\t<\/h3>\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-text  marginbottom-0px\n        \">\n        \t\n            <p>Aplica\u021bi pentru un anumit loc de munc\u0103 sau profita\u021bi de o \u0219ans\u0103 spontan\u0103. Pute\u021bi aplica rapid \u0219i f\u0103r\u0103 un CV. <\/p>\n\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\n                                    <div class=\"img-container\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 12.5 12.5\" xml:space=\"preserve\" width=\"15px\" height=\"15px\">\n  <path d=\"M6.4,0H4.9v3.3h1.5V0z M11,2.5L8.7,4.9L8.2,4.4H8.2L7.7,3.8l2.3-2.3L10.4,2L11,2.5z M12.5,6.2H9.2v1.5h3.3V6.2z M6.6,5.8 l-2.1,6.3L3,10.5l-2,2L0.5,12L0,11.5l2-2L0.5,7.9L6.6,5.8z\" fill=\"currentColor\"><\/path>\n<\/svg>\n<\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div id=\"slide1\" class=\"slide\" data-slide=\"1\">\n                                <div class=\"slide-content\">\n                                \t<div class=\"slide-count\">2<\/div>\n                                \t<div class=\"content-container\">\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-blue font-mini\n            \">\n\t\t\t\t\n            \tPotrivire\n\t\t\t<\/h3>\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-text  marginbottom-0px\n        \">\n        \t\n            <p>Vom \u00eencepe s\u0103 lucr\u0103m la cererea dvs. \u0219i vom vedea dac\u0103 motiva\u021bia \u0219i experien\u021ba dvs. corespund cerin\u021belor postului.<\/p>\n\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\n                                    <div class=\"img-container\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14.3 14.4\" xml:space=\"preserve\" width=\"15px\" height=\"15px\">\n  <path d=\"M11.4,5.9v-3h-3c0-0.1,0-0.1,0-0.2C8.4,1.2,7.2,0,5.7,0C4.2,0,2.9,1.2,2.9,2.7c0,0.1,0,0.1,0,0.2H0v11.4h4.3 c0.3,0,0.7-0.2,0.8-0.5c0.1-0.3,0.1-0.7-0.1-1c-0.1-0.1-0.2-0.3-0.2-0.5c0-0.5,0.4-0.9,0.9-0.9s0.9,0.4,0.9,0.9 c0,0.2-0.1,0.4-0.2,0.5c-0.2,0.3-0.3,0.7-0.1,1c0.1,0.3,0.5,0.5,0.8,0.5h4.3v-3c1.6,0.1,2.9-1.2,2.9-2.7C14.4,7,13,5.8,11.4,5.9z M11.6,9.6c-0.2,0-0.4-0.1-0.5-0.2c-0.3-0.2-0.7-0.3-1-0.1C9.8,9.4,9.6,9.7,9.6,10v2.5H8.4c0-0.1,0-0.1,0-0.2c0-1.5-1.2-2.7-2.7-2.7 c-1.5,0-2.7,1.2-2.7,2.7c0,0.1,0,0.1,0,0.2H1.8V4.8h2.5c0.3,0,0.7-0.2,0.8-0.5c0.1-0.3,0.1-0.7-0.1-1C4.9,3.1,4.8,2.9,4.8,2.7 c0-0.5,0.4-0.9,0.9-0.9s0.9,0.4,0.9,0.9c0,0.2-0.1,0.4-0.2,0.5C6.2,3.6,6.2,4,6.3,4.2c0.1,0.3,0.5,0.5,0.8,0.5h2.5v2.5 c0,0.3,0.2,0.7,0.5,0.8c0.3,0.1,0.7,0.1,1-0.1c0.1-0.1,0.3-0.2,0.5-0.2c0.5,0,0.9,0.4,0.9,0.9C12.5,9.2,12.1,9.6,11.6,9.6z\" fill=\"currentColor\"><\/path>\n<\/svg>\n<\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div id=\"slide2\" class=\"slide\" data-slide=\"2\">\n                                <div class=\"slide-content\">\n                                \t<div class=\"slide-count\">3<\/div>\n                                \t<div class=\"content-container\">\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-blue font-mini\n            \">\n\t\t\t\t\n            \tConversa\u021bie cu IMPACT.\n\t\t\t<\/h3>\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-text  marginbottom-0px\n        \">\n        \t\n            <p>\u00cen\u021belegem c\u0103 un CV nu spune totul: ajungem s\u0103 v\u0103 cunoa\u0219tem \u0219i s\u0103 test\u0103m la ce v\u0103 pricepe\u021bi.<\/p>\n\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\n                                    <div class=\"img-container\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11.2 11.2\" xml:space=\"preserve\" width=\"15px\" height=\"15px\">\n  <path d=\"M11.2,7v3.3v0.8C5.1,11.2,0,6.2,0,0h0.8h3.3l0.7,3.3L3.1,5C3.9,6.2,5,7.3,6.2,8.1l1.6-1.8L11.2,7z\" fill=\"currentColor\"><\/path>\n<\/svg>\n<\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div id=\"slide3\" class=\"slide\" data-slide=\"3\">\n                                <div class=\"slide-content\">\n                                \t<div class=\"slide-count\">4<\/div>\n                                \t<div class=\"content-container\">\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-blue font-mini\n            \">\n\t\t\t\t\n            \tDecizia angajatorului\n\t\t\t<\/h3>\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-text  marginbottom-0px\n        \">\n        \t\n            <p>Prezentarea dvs. poate fi urmat\u0103 de un interviu, dup\u0103 care angajatorul ia decizia final\u0103.<\/p>\n\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\n                                    <div class=\"img-container\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14.5 12.9\" xml:space=\"preserve\" width=\"15px\" height=\"15px\">\n  <path d=\"M0,0v10.8h2l2.3-2.2h1.5C5.9,8,6,7.5,6.2,7.1H3.6L1.5,9.2V1.5h8.6v2.9c0.1,0,0.3,0,0.4,0c0.4,0,0.8,0.1,1.1,0.1V0H0z M8.2,3.4H3.4v1.5h4.8V3.4z M13.8,8.5c-0.2-1.3-1.1-2.3-2.2-2.7c-0.2-0.1-0.4-0.1-0.6-0.2V4.9h-1v0.7C9.1,5.7,8.2,6.2,7.7,7 C7.5,7.5,7.2,7.9,7.2,8.5H6.5v1h0.7c0.2,1.4,1.4,2.6,2.8,2.8v0.7h1v-0.6c1.4-0.2,2.6-1.4,2.8-2.8h0.7V8.5H13.8z M12.7,9.5 c-0.2,0.8-0.9,1.5-1.7,1.7v-0.8h-1v0.8c-0.8-0.2-1.5-0.8-1.7-1.7H9V8.5H8.2c0.1-0.6,0.5-1.1,1-1.4c0.2-0.1,0.4-0.2,0.7-0.3v0.8h1 V6.8c0.2,0.1,0.4,0.1,0.6,0.2c0.6,0.3,0.9,0.8,1.1,1.5h-0.8v1H12.7z\" fill=\"currentColor\"><\/path>\n<\/svg>\n<\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div id=\"slide4\" class=\"slide\" data-slide=\"4\">\n                                <div class=\"slide-content\">\n                                \t<div class=\"slide-count\">5<\/div>\n                                \t<div class=\"content-container\">\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-blue font-mini\n            \">\n\t\t\t\t\n            \tSemnarea contractului\n\t\t\t<\/h3>\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\n        <div class=\"sd-block-text  marginbottom-0px\n        \">\n        \t\n            <p>Aventura ta \u00eencepe acum, felicit\u0103ri! IMPACT se asigur\u0103 c\u0103 totul decurge f\u0103r\u0103 probleme, de la \u00eenfiin\u021bare p\u00e2n\u0103 la plata salariilor. <\/p>\n\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\n                                    <div class=\"img-container\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14.3 12.5\" xml:space=\"preserve\" width=\"15px\" height=\"15px\">\n  <path d=\"M0,0v11.4h2.1L4.5,9h1.6c0.1-0.6,0.2-1.1,0.4-1.6H3.8L1.6,9.7V1.6h9v3c0.1,0,0.3,0,0.4,0c0.4,0,0.8,0.1,1.2,0.1V0.1L0,0L0,0 z M8.6,3.6h-5v1.6h5V3.6z M12.9,7.6V5.9h-4v1.7H7.6v4.9h6.7V7.6H12.9z M10.1,7.1h1.7v0.5h-1.7V7.1z M13.1,11.4H8.7V8.8h4.4V11.4z\" fill=\"currentColor\"><\/path>\n<\/svg>\n<\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n        <\/div>[\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_color=&#8221;bg_white&#8221; css=&#8221;.vc_custom_1760350768123{background-color: bg_white !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;]\n        <div class=\"sd-block-title \">\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left color-dark_gray has-bracket\n            \">\n\t\t\t\t<span class=\"bracket-icon bracket-green\"><svg viewBox=\"0 0 165.66 193.66\" width=\"15px\" height=\"15px\" preserveAspectRatio=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><polygon fill=\"currentColor\" points=\"46.75 168.35 125.45 25.31 151.73 25.31 165.66 0 106.55 0 0 193.66 59.11 193.66 73.04 168.35 46.75 168.35\" \/><\/svg><\/span>\n            \tSpecialit\u0103\u021bile IMPACT.\n\t\t\t<\/h2>\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-30px button-type-background button-size-normal background-color-fluent_yellow\">\n            <a class=\"inner-button\"\n            href=\"https:\/\/impact.be\/ro\/candidati\/toate-posturile-vacante\/\" title=\"Vezi toate locurile de munc\u0103\">\n                <div class=\"button-content\">\n                    <span>Vezi toate locurile de munc\u0103<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>[\/vc_column][vc_column width=&#8221;1\/4&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-60px align-left color-dark_gray mobile_marginbottom-30px\n            \">\n\t\t\t\t\n            \tDomenii de activitate\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-vacancies-grid  marginbottom-0px style-list mobile_marginbottom-30px\n\t\t\">\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-text text-size-normal text-color-dark_gray\">\n            <a class=\"inner-button\"\n            href=\"\/ro\/candidati\/toate-posturile-vacante\/?toBrancheLevel2[0]=8454&toBrancheLevel1[0]=8408\" title=\"Transport\">\n                <div class=\"button-content\">\n                    <span>Transport<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-text text-size-normal text-color-dark_gray\">\n            <a class=\"inner-button\"\n            href=\"\/ro\/candidati\/toate-posturile-vacante\/\" title=\"Toate domeniile\">\n                <div class=\"button-content\">\n                    <span>Toate domeniile<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n        <\/div>[\/vc_column][vc_column width=&#8221;1\/4&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-60px align-left color-dark_gray mobile_marginbottom-30px\n            \">\n\t\t\t\t\n            \tCaracteristici\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-vacancies-grid  marginbottom-0px style-list mobile_marginbottom-30px\n\t\t\">\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-text text-size-normal text-color-dark_gray\">\n            <a class=\"inner-button\"\n            href=\"\/ro\/candidati\/toate-posturile-vacante\/?toFunctionLevel2[0]=7192&toBrancheLevel1[0]=8408\" title=\"\u0218ofer D\">\n                <div class=\"button-content\">\n                    <span>\u0218ofer D<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-text text-size-normal text-color-dark_gray\">\n            <a class=\"inner-button\"\n            href=\"\/ro\/candidati\/toate-posturile-vacante\/?toFunctionLevel2[0]=7187&toBrancheLevel1[0]=8408\" title=\"\u0218ofer C\">\n                <div class=\"button-content\">\n                    <span>\u0218ofer C<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-text text-size-normal text-color-dark_gray\">\n            <a class=\"inner-button\"\n            href=\"\/ro\/candidati\/toate-posturile-vacante\/\" title=\"Toate func\u021biile\">\n                <div class=\"button-content\">\n                    <span>Toate func\u021biile<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n        <\/div>[\/vc_column][vc_column width=&#8221;1\/4&#8243;]\n        <div class=\"sd-block-title \">\n            <h3 class=\"sd-block-title-htag  marginbottom-60px align-left color-dark_gray mobile_marginbottom-30px\n            \">\n\t\t\t\t\n            \tJude\u021be\n\t\t\t<\/h3>\n        <\/div>\n        <div class=\"sd-block-vacancies-grid  marginbottom-0px style-list\n\t\t\">\n        <div class=\"sd-block-button  marginbottom-0px align-left button-type-text text-size-normal text-color-dark_gray\">\n            <a class=\"inner-button\"\n            href=\"\/ro\/candidati\/toate-posturile-vacante\/\" title=\"Toate provinciile\">\n                <div class=\"button-content\">\n                    <span>Toate provinciile<\/span>\n\t\t\t\t    <svg height=\"15\" width=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 15 13.56\"><path fill=\"currentColor\" d=\"M0,5.64h11.64L7.56,0h2.64l4.8,6.84-4.8,6.72h-2.64l4.08-5.64H0v-2.28Z\"\/><\/svg>\n                <\/div>\n            <\/a>\n        <\/div>\n        <\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;bottom&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;image&#8221; row_height=&#8221;row_500px&#8221; bg_color=&#8221;bg_gray&#8221; css=&#8221;.vc_custom_1757059736611{background-color: bg_green !important;}&#8221; bg_custom_img=&#8221;202&#8243;][vc_column width=&#8221;2\/5&#8243;][\/vc_column][vc_column width=&#8221;3\/5&#8243;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_class=&#8221;row-vacancy row-scrollable&#8221;][vc_column width=&#8221;5\/12&#8243; el_class=&#8221;vacancy-overview-column&#8221;][\/vc_column][vc_column width=&#8221;7\/12&#8243; el_class=&#8221;single-job custom-col-enable col-scrollable vacancy-single-column&#8221;][vc_row_inner row_inner_color=&#8221;white&#8221;][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1761311432051{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;10\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_color=&#8221;bg_white&#8221; css=&#8221;.vc_custom_1760350768123{background-color: bg_white !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":10929,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11045","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logistic\u0103 locuri de munc\u0103 \u00een Limburg | IMPACT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logistic\u0103 locuri de munc\u0103 \u00een Limburg | IMPACT\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;bottom&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;image&#8221; row_height=&#8221;row_500px&#8221; bg_color=&#8221;bg_gray&#8221; css=&#8221;.vc_custom_1757059736611{background-color: bg_green !important;}&#8221; bg_custom_img=&#8221;202&#8243;][vc_column width=&#8221;2\/5&#8243;][\/vc_column][vc_column width=&#8221;3\/5&#8243;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_class=&#8221;row-vacancy row-scrollable&#8221;][vc_column width=&#8221;5\/12&#8243; el_class=&#8221;vacancy-overview-column&#8221;][\/vc_column][vc_column width=&#8221;7\/12&#8243; el_class=&#8221;single-job custom-col-enable col-scrollable vacancy-single-column&#8221;][vc_row_inner row_inner_color=&#8221;white&#8221;][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1761311432051{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;10\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_color=&#8221;bg_white&#8221; css=&#8221;.vc_custom_1760350768123{background-color: bg_white !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/\" \/>\n<meta property=\"og:site_name\" content=\"IMPACT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jobs.impact\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T11:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/impact.be\/wp-content\/uploads\/2025\/11\/Social-share.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucrul-in-logistica-si-transport\\\/logistica-locuri-de-munca-in-limburg\\\/\",\"url\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucrul-in-logistica-si-transport\\\/logistica-locuri-de-munca-in-limburg\\\/\",\"name\":\"Logistic\u0103 locuri de munc\u0103 \u00een Limburg | IMPACT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/#website\"},\"datePublished\":\"2025-10-07T08:59:21+00:00\",\"dateModified\":\"2025-12-18T11:10:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucrul-in-logistica-si-transport\\\/logistica-locuri-de-munca-in-limburg\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucrul-in-logistica-si-transport\\\/logistica-locuri-de-munca-in-limburg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucrul-in-logistica-si-transport\\\/logistica-locuri-de-munca-in-limburg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/impact.be\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candida\u021bi\",\"item\":\"https:\\\/\\\/impact.be\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lucrul \u00een logistic\u0103 \u0219i transport\",\"item\":\"https:\\\/\\\/impact.be\\\/ro\\\/candidati\\\/lucrul-in-logistica-si-transport\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Logistic\u0103 locuri de munc\u0103 \u00een Limburg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/impact.be\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/impact.be\\\/ro\\\/\",\"name\":\"IMPACT\",\"description\":\"Impact website\",\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logistic\u0103 locuri de munc\u0103 \u00een Limburg | IMPACT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/","og_locale":"ro_RO","og_type":"article","og_title":"Logistic\u0103 locuri de munc\u0103 \u00een Limburg | IMPACT","og_description":"[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;bottom&#8221; bg_custom_divider=&#8221;diagonal-60&#8243; bg_custom_style=&#8221;image&#8221; row_height=&#8221;row_500px&#8221; bg_color=&#8221;bg_gray&#8221; css=&#8221;.vc_custom_1757059736611{background-color: bg_green !important;}&#8221; bg_custom_img=&#8221;202&#8243;][vc_column width=&#8221;2\/5&#8243;][\/vc_column][vc_column width=&#8221;3\/5&#8243;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_class=&#8221;row-vacancy row-scrollable&#8221;][vc_column width=&#8221;5\/12&#8243; el_class=&#8221;vacancy-overview-column&#8221;][\/vc_column][vc_column width=&#8221;7\/12&#8243; el_class=&#8221;single-job custom-col-enable col-scrollable vacancy-single-column&#8221;][vc_row_inner row_inner_color=&#8221;white&#8221;][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1761311432051{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;10\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_color=&#8221;bg_white&#8221; css=&#8221;.vc_custom_1760350768123{background-color: bg_white !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]","og_url":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/","og_site_name":"IMPACT","article_publisher":"https:\/\/www.facebook.com\/jobs.impact","article_modified_time":"2025-12-18T11:10:38+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/impact.be\/wp-content\/uploads\/2025\/11\/Social-share.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"4 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/","url":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/","name":"Logistic\u0103 locuri de munc\u0103 \u00een Limburg | IMPACT","isPartOf":{"@id":"https:\/\/impact.be\/ro\/#website"},"datePublished":"2025-10-07T08:59:21+00:00","dateModified":"2025-12-18T11:10:38+00:00","breadcrumb":{"@id":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/logistica-locuri-de-munca-in-limburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/impact.be\/ro\/"},{"@type":"ListItem","position":2,"name":"Candida\u021bi","item":"https:\/\/impact.be\/ro\/"},{"@type":"ListItem","position":3,"name":"Lucrul \u00een logistic\u0103 \u0219i transport","item":"https:\/\/impact.be\/ro\/candidati\/lucrul-in-logistica-si-transport\/"},{"@type":"ListItem","position":4,"name":"Logistic\u0103 locuri de munc\u0103 \u00een Limburg"}]},{"@type":"WebSite","@id":"https:\/\/impact.be\/ro\/#website","url":"https:\/\/impact.be\/ro\/","name":"IMPACT","description":"Impact website","inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/11045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/comments?post=11045"}],"version-history":[{"count":8,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/11045\/revisions"}],"predecessor-version":[{"id":11063,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/11045\/revisions\/11063"}],"up":[{"embeddable":true,"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/pages\/10929"}],"wp:attachment":[{"href":"https:\/\/impact.be\/ro\/wp-json\/wp\/v2\/media?parent=11045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}